{"id":48579,"date":"2024-10-05T13:14:17","date_gmt":"2024-10-05T11:14:17","guid":{"rendered":"https:\/\/fundesplai.org\/informa-t\/\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\/"},"modified":"2022-10-05T13:14:17","modified_gmt":"2022-10-05T11:14:17","slug":"4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros","status":"publish","type":"post","link":"https:\/\/fundesplai.org\/es\/informa-t\/sostenibilidad\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\/","title":{"rendered":"4 ideas para celebrar el D\u00eda Mundial de los P\u00e1jaros"},"content":{"rendered":"<p>El D\u00eda Mundial de las Aves es una fecha internacional que se celebra cada a\u00f1o el 5 de octubre. Esta fecha fue establecida por la Uni\u00f3n Internacional para la Conservaci\u00f3n de la Naturaleza (UICN) en el a\u00f1o 1963, con el objetivo de concienciar sobre la importancia de conservar las aves y su h\u00e1bitat. Se eligi\u00f3 este d\u00eda porque coincide con la migraci\u00f3n masiva de aves que atraviesan el hemisferio sur. Las aves son esenciales para el equilibrio de los ecosistemas, ya que son polacos, dispersos de semillas y depredadores naturales. Y, adem\u00e1s, son un gran indicador del buen estado de los ecosistemas,&#8230;<\/p>\n<p class=\"planet-fundesplai-llegeix-mes-wrapper et_pb_module et_pb_button_module_wrapper\"><a href=\"https:\/\/cases.fundesplai.org\/blog\/animals\/4-idees-per-celebrar-el-dia-mundial-dels-ocells\/\" class=\"et_pb_button planet-fundesplai-llegeix-mes\">Lee m\u00e1s en el blog de Casas de colonias<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El D\u00eda Mundial de las Aves es una fecha internacional que se celebra cada a\u00f1o el 5 de octubre. Esta fecha fue establecida por la Uni\u00f3n Internacional para la Conservaci\u00f3n de la Naturaleza (UICN) en el a\u00f1o 1963, con el objetivo de concienciar sobre la importancia de conservar las aves y su h\u00e1bitat. Se eligi\u00f3 este [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[996],"tags":[],"class_list":["post-48579","post","type-post","status-publish","format-standard","hentry","category-sostenibilidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 ideas para celebrar el D\u00eda Mundial de los P\u00e1jaros - Fundesplai<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 ideas para celebrar el D\u00eda Mundial de los P\u00e1jaros - Fundesplai\" \/>\n<meta property=\"og:description\" content=\"El D\u00eda Mundial de las Aves es una fecha internacional que se celebra cada a\u00f1o el 5 de octubre. Esta fecha fue establecida por la Uni\u00f3n Internacional para la Conservaci\u00f3n de la Naturaleza (UICN) en el a\u00f1o 1963, con el objetivo de concienciar sobre la importancia de conservar las aves y su h\u00e1bitat. Se eligi\u00f3 este [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundesplai.org\/es\/informa-t\/sostenibilidad\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundesplai\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-05T11:14:17+00:00\" \/>\n<meta name=\"author\" content=\"jpasquier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jpasquier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/sostenibilidad\\\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/sostenibilidad\\\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\\\/\"},\"author\":{\"name\":\"jpasquier\",\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/dc7af2fbad61a0644ec89f4df8f08854\"},\"headline\":\"4 ideas para celebrar el D\u00eda Mundial de los P\u00e1jaros\",\"datePublished\":\"2024-10-05T11:14:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/sostenibilidad\\\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\\\/\"},\"wordCount\":130,\"articleSection\":[\"Sostenibilidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/sostenibilidad\\\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\\\/\",\"url\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/sostenibilidad\\\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\\\/\",\"name\":\"4 ideas para celebrar el D\u00eda Mundial de los P\u00e1jaros - Fundesplai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/#website\"},\"datePublished\":\"2024-10-05T11:14:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/dc7af2fbad61a0644ec89f4df8f08854\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/sostenibilidad\\\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/sostenibilidad\\\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/sostenibilidad\\\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inf\u00f3rmate\",\"item\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informate\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sostenibilidad\",\"item\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/category\\\/sostenibilidad\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"4 ideas para celebrar el D\u00eda Mundial de los P\u00e1jaros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/\",\"name\":\"Fundesplai\",\"description\":\"Eduquem per la conviv\u00e8ncia i la sostenibilitat\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/dc7af2fbad61a0644ec89f4df8f08854\",\"name\":\"jpasquier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e20ef130c6707e41cf2bfba9d7fddcbe2dbb8f8cb76952c65cdd3e6432ff7a52?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e20ef130c6707e41cf2bfba9d7fddcbe2dbb8f8cb76952c65cdd3e6432ff7a52?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e20ef130c6707e41cf2bfba9d7fddcbe2dbb8f8cb76952c65cdd3e6432ff7a52?s=96&d=mm&r=g\",\"caption\":\"jpasquier\"},\"url\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/author\\\/jpasquier\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 ideas para celebrar el D\u00eda Mundial de los P\u00e1jaros - Fundesplai","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"4 ideas para celebrar el D\u00eda Mundial de los P\u00e1jaros - Fundesplai","og_description":"El D\u00eda Mundial de las Aves es una fecha internacional que se celebra cada a\u00f1o el 5 de octubre. Esta fecha fue establecida por la Uni\u00f3n Internacional para la Conservaci\u00f3n de la Naturaleza (UICN) en el a\u00f1o 1963, con el objetivo de concienciar sobre la importancia de conservar las aves y su h\u00e1bitat. Se eligi\u00f3 este [...]","og_url":"https:\/\/fundesplai.org\/es\/informa-t\/sostenibilidad\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\/","og_site_name":"Fundesplai","article_published_time":"2024-10-05T11:14:17+00:00","author":"jpasquier","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jpasquier","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundesplai.org\/es\/informa-t\/sostenibilidad\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\/#article","isPartOf":{"@id":"https:\/\/fundesplai.org\/es\/informa-t\/sostenibilidad\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\/"},"author":{"name":"jpasquier","@id":"https:\/\/fundesplai.org\/es\/#\/schema\/person\/dc7af2fbad61a0644ec89f4df8f08854"},"headline":"4 ideas para celebrar el D\u00eda Mundial de los P\u00e1jaros","datePublished":"2024-10-05T11:14:17+00:00","mainEntityOfPage":{"@id":"https:\/\/fundesplai.org\/es\/informa-t\/sostenibilidad\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\/"},"wordCount":130,"articleSection":["Sostenibilidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fundesplai.org\/es\/informa-t\/sostenibilidad\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\/","url":"https:\/\/fundesplai.org\/es\/informa-t\/sostenibilidad\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\/","name":"4 ideas para celebrar el D\u00eda Mundial de los P\u00e1jaros - Fundesplai","isPartOf":{"@id":"https:\/\/fundesplai.org\/es\/#website"},"datePublished":"2024-10-05T11:14:17+00:00","author":{"@id":"https:\/\/fundesplai.org\/es\/#\/schema\/person\/dc7af2fbad61a0644ec89f4df8f08854"},"breadcrumb":{"@id":"https:\/\/fundesplai.org\/es\/informa-t\/sostenibilidad\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundesplai.org\/es\/informa-t\/sostenibilidad\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fundesplai.org\/es\/informa-t\/sostenibilidad\/4-ideas-para-celebrar-el-dia-mundial-de-los-pajaros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/fundesplai.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Inf\u00f3rmate","item":"https:\/\/fundesplai.org\/es\/informate\/"},{"@type":"ListItem","position":3,"name":"Sostenibilidad","item":"https:\/\/fundesplai.org\/es\/informa-t\/category\/sostenibilidad\/"},{"@type":"ListItem","position":4,"name":"4 ideas para celebrar el D\u00eda Mundial de los P\u00e1jaros"}]},{"@type":"WebSite","@id":"https:\/\/fundesplai.org\/es\/#website","url":"https:\/\/fundesplai.org\/es\/","name":"Fundesplai","description":"Eduquem per la conviv\u00e8ncia i la sostenibilitat","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/fundesplai.org\/es\/#\/schema\/person\/dc7af2fbad61a0644ec89f4df8f08854","name":"jpasquier","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e20ef130c6707e41cf2bfba9d7fddcbe2dbb8f8cb76952c65cdd3e6432ff7a52?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e20ef130c6707e41cf2bfba9d7fddcbe2dbb8f8cb76952c65cdd3e6432ff7a52?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e20ef130c6707e41cf2bfba9d7fddcbe2dbb8f8cb76952c65cdd3e6432ff7a52?s=96&d=mm&r=g","caption":"jpasquier"},"url":"https:\/\/fundesplai.org\/es\/informa-t\/author\/jpasquier\/"}]}},"_links":{"self":[{"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/48579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=48579"}],"version-history":[{"count":0,"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/48579\/revisions"}],"wp:attachment":[{"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=48579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=48579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=48579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}