{"id":48309,"date":"2023-04-18T15:52:29","date_gmt":"2023-04-18T13:52:29","guid":{"rendered":"https:\/\/fundesplai.org\/informa-t\/sense-categoria\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/"},"modified":"2023-10-02T10:57:12","modified_gmt":"2023-10-02T08:57:12","slug":"10-guias-de-cuentos-para-ninos-as-y-adolescentes","status":"publish","type":"post","link":"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/","title":{"rendered":"10 gu\u00edas de cuentos para ni\u00f1os\/as y adolescentes"},"content":{"rendered":"<p>\u00bfEst\u00e1s a punto para que los ni\u00f1os y ni\u00f1as o adolescentes que tienes por casa se sumerjan en el mundo m\u00e1gico de los cuentos, libros y novelas? Hoy te hacemos una propuesta especialmente pensada para festividades como el Sant Jordi y en general para promover la lectura entre los ni\u00f1os y j\u00f3venes: 10 gu\u00edas con selecciones de cuentos hechas por Fundesplai para que encuentres lo que necesitas siguiendo nuestros valores. Las historias que aparecen en los cuentos y novelas tienen el poder de transportarnos a lugares muy lejanos, impregnarnos de valores y hacer despertar nuestra imaginaci\u00f3n! En este caso, en&#8230;<\/p>\n<p class=\"planet-fundesplai-llegeix-mes-wrapper et_pb_module et_pb_button_module_wrapper\"><a href=\"https:\/\/cases.fundesplai.org\/blog\/familia\/10-guies-de-contes\/\" class=\"et_pb_button planet-fundesplai-llegeix-mes\">Lee m\u00e1s en el blog de Casas de colonias<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy llevamos una entrada de blog muy especial donde hacemos una recopilaci\u00f3n de diferentes ideas de cuentos para ni\u00f1os y ni\u00f1as y adolescentes!<\/p>\n","protected":false},"author":9,"featured_media":44681,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[995],"tags":[],"class_list":["post-48309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-propuestas-para-familias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 gu\u00edas de cuentos para ni\u00f1os\/as y adolescentes - Fundesplai<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 gu\u00edas de cuentos para ni\u00f1os\/as y adolescentes - Fundesplai\" \/>\n<meta property=\"og:description\" content=\"Hoy llevamos una entrada de blog muy especial donde hacemos una recopilaci\u00f3n de diferentes ideas de cuentos para ni\u00f1os y ni\u00f1as y adolescentes!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundesplai\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-18T13:52:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-02T08:57:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fundesplai.org\/wp-content\/uploads\/2023\/04\/Guies-de-contes-biblioteca-Fundesplai.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1888\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alfons Valle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alfons Valle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/propuestas-para-familias\\\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/propuestas-para-familias\\\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\\\/\"},\"author\":{\"name\":\"Alfons Valle\",\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/c0e9e7466bb8ac06f5264324a6109733\"},\"headline\":\"10 gu\u00edas de cuentos para ni\u00f1os\\\/as y adolescentes\",\"datePublished\":\"2023-04-18T13:52:29+00:00\",\"dateModified\":\"2023-10-02T08:57:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/propuestas-para-familias\\\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\\\/\"},\"wordCount\":127,\"image\":{\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/propuestas-para-familias\\\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fundesplai.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Guies-de-contes-biblioteca-Fundesplai.jpg\",\"articleSection\":[\"Propuestas para familias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/propuestas-para-familias\\\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\\\/\",\"url\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/propuestas-para-familias\\\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\\\/\",\"name\":\"10 gu\u00edas de cuentos para ni\u00f1os\\\/as y adolescentes - Fundesplai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/propuestas-para-familias\\\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/propuestas-para-familias\\\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fundesplai.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Guies-de-contes-biblioteca-Fundesplai.jpg\",\"datePublished\":\"2023-04-18T13:52:29+00:00\",\"dateModified\":\"2023-10-02T08:57:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/c0e9e7466bb8ac06f5264324a6109733\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/propuestas-para-familias\\\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/propuestas-para-familias\\\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/propuestas-para-familias\\\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fundesplai.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Guies-de-contes-biblioteca-Fundesplai.jpg\",\"contentUrl\":\"https:\\\/\\\/fundesplai.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Guies-de-contes-biblioteca-Fundesplai.jpg\",\"width\":1888,\"height\":900,\"caption\":\"binary comment\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/propuestas-para-familias\\\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inf\u00f3rmate\",\"item\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informate\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Propuestas para familias\",\"item\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/category\\\/propuestas-para-familias\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"10 gu\u00edas de cuentos para ni\u00f1os\\\/as y adolescentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/\",\"name\":\"Fundesplai\",\"description\":\"Eduquem per la conviv\u00e8ncia i la sostenibilitat\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/c0e9e7466bb8ac06f5264324a6109733\",\"name\":\"Alfons Valle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71d95a3f99a068ba570ac1314ed6911a59c5ae3f22ffcf23631cd1a861a640bc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71d95a3f99a068ba570ac1314ed6911a59c5ae3f22ffcf23631cd1a861a640bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71d95a3f99a068ba570ac1314ed6911a59c5ae3f22ffcf23631cd1a861a640bc?s=96&d=mm&r=g\",\"caption\":\"Alfons Valle\"},\"url\":\"https:\\\/\\\/fundesplai.org\\\/es\\\/informa-t\\\/author\\\/avalle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 gu\u00edas de cuentos para ni\u00f1os\/as y adolescentes - Fundesplai","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/","og_locale":"es_ES","og_type":"article","og_title":"10 gu\u00edas de cuentos para ni\u00f1os\/as y adolescentes - Fundesplai","og_description":"Hoy llevamos una entrada de blog muy especial donde hacemos una recopilaci\u00f3n de diferentes ideas de cuentos para ni\u00f1os y ni\u00f1as y adolescentes!","og_url":"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/","og_site_name":"Fundesplai","article_published_time":"2023-04-18T13:52:29+00:00","article_modified_time":"2023-10-02T08:57:12+00:00","og_image":[{"width":1888,"height":900,"url":"https:\/\/fundesplai.org\/wp-content\/uploads\/2023\/04\/Guies-de-contes-biblioteca-Fundesplai.jpg","type":"image\/jpeg"}],"author":"Alfons Valle","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Alfons Valle","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/#article","isPartOf":{"@id":"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/"},"author":{"name":"Alfons Valle","@id":"https:\/\/fundesplai.org\/es\/#\/schema\/person\/c0e9e7466bb8ac06f5264324a6109733"},"headline":"10 gu\u00edas de cuentos para ni\u00f1os\/as y adolescentes","datePublished":"2023-04-18T13:52:29+00:00","dateModified":"2023-10-02T08:57:12+00:00","mainEntityOfPage":{"@id":"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/"},"wordCount":127,"image":{"@id":"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/#primaryimage"},"thumbnailUrl":"https:\/\/fundesplai.org\/wp-content\/uploads\/2023\/04\/Guies-de-contes-biblioteca-Fundesplai.jpg","articleSection":["Propuestas para familias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/","url":"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/","name":"10 gu\u00edas de cuentos para ni\u00f1os\/as y adolescentes - Fundesplai","isPartOf":{"@id":"https:\/\/fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/#primaryimage"},"image":{"@id":"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/#primaryimage"},"thumbnailUrl":"https:\/\/fundesplai.org\/wp-content\/uploads\/2023\/04\/Guies-de-contes-biblioteca-Fundesplai.jpg","datePublished":"2023-04-18T13:52:29+00:00","dateModified":"2023-10-02T08:57:12+00:00","author":{"@id":"https:\/\/fundesplai.org\/es\/#\/schema\/person\/c0e9e7466bb8ac06f5264324a6109733"},"breadcrumb":{"@id":"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/#primaryimage","url":"https:\/\/fundesplai.org\/wp-content\/uploads\/2023\/04\/Guies-de-contes-biblioteca-Fundesplai.jpg","contentUrl":"https:\/\/fundesplai.org\/wp-content\/uploads\/2023\/04\/Guies-de-contes-biblioteca-Fundesplai.jpg","width":1888,"height":900,"caption":"binary comment"},{"@type":"BreadcrumbList","@id":"https:\/\/fundesplai.org\/es\/informa-t\/propuestas-para-familias\/10-guias-de-cuentos-para-ninos-as-y-adolescentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/fundesplai.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Inf\u00f3rmate","item":"https:\/\/fundesplai.org\/es\/informate\/"},{"@type":"ListItem","position":3,"name":"Propuestas para familias","item":"https:\/\/fundesplai.org\/es\/informa-t\/category\/propuestas-para-familias\/"},{"@type":"ListItem","position":4,"name":"10 gu\u00edas de cuentos para ni\u00f1os\/as y adolescentes"}]},{"@type":"WebSite","@id":"https:\/\/fundesplai.org\/es\/#website","url":"https:\/\/fundesplai.org\/es\/","name":"Fundesplai","description":"Eduquem per la conviv\u00e8ncia i la sostenibilitat","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/fundesplai.org\/es\/#\/schema\/person\/c0e9e7466bb8ac06f5264324a6109733","name":"Alfons Valle","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/71d95a3f99a068ba570ac1314ed6911a59c5ae3f22ffcf23631cd1a861a640bc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71d95a3f99a068ba570ac1314ed6911a59c5ae3f22ffcf23631cd1a861a640bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71d95a3f99a068ba570ac1314ed6911a59c5ae3f22ffcf23631cd1a861a640bc?s=96&d=mm&r=g","caption":"Alfons Valle"},"url":"https:\/\/fundesplai.org\/es\/informa-t\/author\/avalle\/"}]}},"_links":{"self":[{"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/48309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=48309"}],"version-history":[{"count":1,"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/48309\/revisions"}],"predecessor-version":[{"id":56006,"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/48309\/revisions\/56006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/media\/44681"}],"wp:attachment":[{"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=48309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=48309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=48309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}